{"id":1135,"date":"2024-11-06T20:14:26","date_gmt":"2024-11-06T18:14:26","guid":{"rendered":"https:\/\/www.monelladvocats.com\/?page_id=1135"},"modified":"2025-10-13T10:38:17","modified_gmt":"2025-10-13T08:38:17","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/www.monelladvocats.com\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"<ol>\n<li><strong> INFORMACI\u00d3N AL USUARIO<\/strong><\/li>\n<\/ol>\n<p><strong>\u00bfQui\u00e9n es el responsable del tratamiento de tus datos personales?<br \/>\n<\/strong><\/p>\n<p><strong>MAR MONELL COROMINES<\/strong>\u00a0es el RESPONSABLE del tratamiento de los datos personales del USUARIO y te informa de que estos datos ser\u00e1n tratados de conformidad con lo dispuesto en el Reglamento (UE) 2016\/679, de 27 de abril (RGPD), y la Ley Org\u00e1nica 3\/2018, de 5 de diciembre (LOPDGDD).<\/p>\n<p><strong>\u00bfPara qu\u00e9 tratamos tus datos personales?<br \/>\n<\/strong>Para mantener una relaci\u00f3n comercial con el usuario. Las operaciones previstas para realizar el tratamiento son:<\/p>\n<ul>\n<li>Remisi\u00f3n de comunicaciones comerciales publicitarias por e-mail, fax, SMS, MMS, redes sociales o cualquier otro medio electr\u00f3nico o f\u00edsico, presente o futuro, que posibilite realizar comunicaciones comerciales. Estas comunicaciones ser\u00e1n realizadas por el RESPONSABLE y estar\u00e1n relacionadas con sus productos y servicios, o de sus colaboradores o proveedores, con los que este haya alcanzado alg\u00fan acuerdo de promoci\u00f3n. En este caso, los terceros nunca tendr\u00e1n acceso a los datos personales.<\/li>\n<li>Realizar estudios de mercado y an\u00e1lisis estad\u00edsticos.<\/li>\n<li>Tramitar encargos, solicitudes, dar respuesta a las consultas o cualquier tipo de petici\u00f3n que sea realizada por el USUARIO a trav\u00e9s de cualquiera de las formas de contacto que se ponen a su disposici\u00f3n en la p\u00e1gina web del RESPONSABLE.<\/li>\n<li>Remitir el bolet\u00edn informativo online sobre novedades, ofertas y promociones en nuestra actividad<strong>.<\/strong><\/li>\n<\/ul>\n<p><strong>\u00bfPor qu\u00e9 motivo podemos tratar tus datos personales?<\/strong><\/p>\n<p>Porque el tratamiento est\u00e1 legitimado por el art\u00edculo 6 del GDPR de la siguiente forma:<\/p>\n<ul>\n<li>Con el consentimiento del USUARIO: remisi\u00f3n de comunicaciones comerciales y del bolet\u00edn informativo.<\/li>\n<li>Por inter\u00e9s leg\u00edtimo del RESPONSABLE: realizar estudios de mercado, an\u00e1lisis estad\u00edsticos, etc. y tramitar encargos, solicitudes, etc. a petici\u00f3n del USUARIO.<\/li>\n<\/ul>\n<p><strong>\u00bfDurante cu\u00e1nto tiempo guardaremos tus datos personales?<br \/>\n<\/strong>Se conservar\u00e1n durante no m\u00e1s tiempo del necesario para mantener el fin del tratamiento o existan prescripciones legales que dictaminen su custodia y, cuando ya no sea necesario para ello, se suprimir\u00e1n con medidas de seguridad adecuadas para garantizar la anonimizaci\u00f3n de los datos o la destrucci\u00f3n total de los mismos.<br \/>\n<strong><br \/>\n\u00bfA qui\u00e9n facilitamos tus datos personales?<\/strong><\/p>\n<p>No est\u00e1 prevista ninguna comunicaci\u00f3n de datos personales a terceros salvo, si fuese necesario para el desarrollo y ejecuci\u00f3n de las finalidades del tratamiento, a nuestros proveedores de servicios relacionados con comunicaciones, con los cuales el RESPONSABLE tiene suscritos los contratos de confidencialidad y de encargado de tratamiento exigidos por la normativa vigente de privacidad.<\/p>\n<p><strong>\u00bfCu\u00e1les son tus derechos?<br \/>\n<\/strong>Los derechos que asisten al USUARIO son:<\/p>\n<ul>\n<li>Derecho a retirar el consentimiento en cualquier momento.<\/li>\n<li>Derecho de acceso, rectificaci\u00f3n, portabilidad y supresi\u00f3n de sus datos, y de limitaci\u00f3n u oposici\u00f3n a su tratamiento.<\/li>\n<li>Derecho a presentar una reclamaci\u00f3n ante la autoridad de control (www.aepd.es) si considera que el tratamiento no se ajusta a la normativa vigente.<\/li>\n<\/ul>\n<p><strong>Datos de contacto para ejercer tus derechos<\/strong>: MAR MONELL COROMINES. Carretera de Vic 25-31, entresuelo 5, 08242 Manresa (Barcelona).<br \/>\nE-mail:\u00a0<a href=\"mailto:monica@monelladvocats.com\">monica@monelladvocats.com<\/a><\/p>\n<ol start=\"2\">\n<li><strong> CAR\u00c1CTER OBLIGATORIO O FACULTATIVO DE LA INFORMACI\u00d3N FACILITADA POR EL USUARIO<br \/>\n<\/strong>Los USUARIOS, mediante la marcaci\u00f3n de las casillas correspondientes y la entrada de datos en los campos marcados con un asterisco (*) en el formulario de contacto o presentados en formularios de descarga, aceptan expresamente y de forma libre e inequ\u00edvoca que sus datos son necesarios para atender su petici\u00f3n, por parte del prestador, siendo voluntaria la inclusi\u00f3n de datos en los campos restantes. El USUARIO garantiza que los datos personales facilitados al RESPONSABLE son veraces y se hace responsable de comunicar cualquier modificaci\u00f3n de los mismos.<\/li>\n<\/ol>\n<p>El RESPONSABLE informa de que todos los datos solicitados a trav\u00e9s del sitio web son obligatorios, ya que son necesarios para la prestaci\u00f3n de un servicio \u00f3ptimo al USUARIO. En caso de que no se faciliten todos los datos, no se garantiza que la informaci\u00f3n y servicios facilitados sean completamente ajustados a sus necesidades.<\/p>\n<ol start=\"3\">\n<li><strong> MEDIDAS DE SEGURIDAD<\/strong><\/li>\n<\/ol>\n<p>Que de conformidad con lo dispuesto en las normativas vigentes en protecci\u00f3n de datos personales, el RESPONSABLE est\u00e1 cumpliendo con todas las disposiciones de las normativas RGPD y LOPDGDD para el tratamiento de los datos personales de su responsabilidad, y manifiestamente con los principios descritos en el art\u00edculo 5 del RGPD, por los cuales son tratados de manera l\u00edcita, leal y transparente en relaci\u00f3n con el interesado y adecuados, pertinentes y limitados a lo necesario en relaci\u00f3n con los fines para los que son tratados.<\/p>\n<p>El RESPONSABLE garantiza que ha implementado pol\u00edticas t\u00e9cnicas y organizativas apropiadas para aplicar las medidas de seguridad que establecen el RGPD y la LOPDGDD con el fin de proteger los derechos y libertades de los USUARIOS y les ha comunicado la informaci\u00f3n adecuada para que puedan ejercerlos.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre las garant\u00edas de privacidad, puedes dirigirte al RESPONSABLE a trav\u00e9s de MAR MONELL COROMINES, carretera de Vic 25-31, entresuelo 5, 08242 Manresa (Barcelona). E-mail: <a href=\"mailto:monica@monelladvocats.com\">monica@monelladvocats.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>INFORMACI\u00d3N AL USUARIO \u00bfQui\u00e9n es el responsable del tratamiento de tus datos personales? MAR MONELL COROMINES\u00a0es el RESPONSABLE del tratamiento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"narrow-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1135","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.monelladvocats.com\/es\/wp-json\/wp\/v2\/pages\/1135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monelladvocats.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.monelladvocats.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.monelladvocats.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monelladvocats.com\/es\/wp-json\/wp\/v2\/comments?post=1135"}],"version-history":[{"count":2,"href":"https:\/\/www.monelladvocats.com\/es\/wp-json\/wp\/v2\/pages\/1135\/revisions"}],"predecessor-version":[{"id":1139,"href":"https:\/\/www.monelladvocats.com\/es\/wp-json\/wp\/v2\/pages\/1135\/revisions\/1139"}],"wp:attachment":[{"href":"https:\/\/www.monelladvocats.com\/es\/wp-json\/wp\/v2\/media?parent=1135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}